{"id":276,"date":"2024-05-29T13:17:08","date_gmt":"2024-05-29T11:17:08","guid":{"rendered":"https:\/\/maveingenieros.com\/?page_id=276"},"modified":"2024-05-29T13:17:37","modified_gmt":"2024-05-29T11:17:37","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/maveingenieros.com\/en\/aviso-legal\/","title":{"rendered":"Aviso legal"},"content":{"rendered":"<h4 class=\"wp-block-heading\"><strong><a href=\"http:\/\/maveingenieros.com\/en\/\">maveingenieros.com<\/a><\/strong><\/h4>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>I. INFORMACI\u00d3N GENERAL<\/strong><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">\u200b<\/h3>\n\n\n\n<p>En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y el Comercio Electr\u00f3nico (LSSI-CE) de 11 de julio, se facilitan a continuaci\u00f3n los siguientes datos de informaci\u00f3n general de este sitio web:<\/p>\n\n\n\n<p>La titularidad de este sitio web,&nbsp;<strong>maveingenieros.com<\/strong>, (en adelante, Sitio Web) la ostenta:&nbsp;<strong>MAVE INGENIEROS, S.L.<\/strong>, provista de&nbsp;<strong>NIF: B-81339483<\/strong>&nbsp;e inscrita en: Registro Mercantil de Madrid con los siguientes datos registrales: Tomo 10319, libro 0, folio 177, secci\u00f3n 8\u00aa, cuyo representante es: Manuel Vega, y cuyos datos de contacto son:<\/p>\n\n\n\n<p>Direcci\u00f3n: C\/ San Jose, 6 nave 2<\/p>\n\n\n\n<p>Tel\u00e9fono de contacto: 916928520<\/p>\n\n\n\n<p>Email de contacto:&nbsp;<strong>mvega@maveingenieros.com<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>II. T\u00c9RMINOS Y CONDICIONES GENERALES DE USO<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">El objeto de las condiciones: El Sitio Web<\/h4>\n\n\n\n<h4 class=\"wp-block-heading\">\u200b<\/h4>\n\n\n\n<p>El objeto de las presentes Condiciones Generales de Uso (en adelante, Condiciones) es regular el acceso y la utilizaci\u00f3n del Sitio Web. A los efectos de las presentes Condiciones se entender\u00e1 como Sitio Web: la apariencia externa de los interfaces de pantalla, tanto de forma est\u00e1tica como de forma din\u00e1mica, es decir, el \u00e1rbol de navegaci\u00f3n; y todos los elementos integrados tanto en los interfaces de pantalla como en el \u00e1rbol de navegaci\u00f3n (en adelante, Contenidos) y todos aquellos servicios o recursos en l\u00ednea que en su caso ofrezca a los Usuarios (en adelante, Servicios).<\/p>\n\n\n\n<p><strong>MAVE INGENIEROS<\/strong>&nbsp;se reserva la facultad de modificar, en cualquier momento, y sin aviso previo, la presentaci\u00f3n y configuraci\u00f3n del Sitio Web y de los Contenidos y Servicios que en \u00e9l pudieran estar incorporados. El Usuario reconoce y acepta que en cualquier momento&nbsp;<strong>MAVE INGENIEROS<\/strong>&nbsp;pueda interrumpir, desactivar y\/o cancelar cualquiera de estos elementos que se integran en el Sitio Web o el acceso a los mismos.<\/p>\n\n\n\n<p>El acceso al Sitio Web por el Usuario tiene car\u00e1cter libre y, por regla general, es gratuito sin que el Usuario tenga que proporcionar una contraprestaci\u00f3n para poder disfrutar de ello, salvo en lo relativo al coste de conexi\u00f3n a trav\u00e9s de la red de telecomunicaciones suministrada por el proveedor de acceso que hubiere contratado el Usuario.<\/p>\n\n\n\n<p>La utilizaci\u00f3n de alguno de los Contenidos o Servicios del Sitio Web podr\u00e1 hacerse mediante la suscripci\u00f3n o registro previo del Usuario.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><\/h4>\n\n\n\n<h4 class=\"wp-block-heading\"><\/h4>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>El USUARIO<\/strong><\/h4>\n\n\n\n<h4 class=\"wp-block-heading\">\u200b<\/h4>\n\n\n\n<p>El acceso, la navegaci\u00f3n y uso del Sitio Web, confiere la condici\u00f3n de Usuario, por lo que se aceptan, desde que se inicia la navegaci\u00f3n por el Sitio Web, todas las Condiciones aqu\u00ed establecidas, as\u00ed como sus ulteriores modificaciones, sin perjuicio de la aplicaci\u00f3n de la correspondiente normativa legal de obligado cumplimiento seg\u00fan el caso. Dada la relevancia de lo anterior, se recomienda al Usuario leerlas cada vez que visite el Sitio Web.<\/p>\n\n\n\n<p>El Sitio Web de&nbsp;<strong>MAVE INGENIEROS<\/strong>&nbsp;proporciona gran diversidad de informaci\u00f3n, servicios y datos. El Usuario asume su responsabilidad para realizar un uso correcto del Sitio Web. Esta responsabilidad se extender\u00e1 a:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Un uso de la informaci\u00f3n, Contenidos y\/o Servicios y datos ofrecidos por\u00a0<strong>MAVE INGENIEROS<\/strong>\u00a0sin que sea contrario a lo dispuesto por las presentes Condiciones, la Ley, la moral o el orden p\u00fablico, o que de cualquier otro modo puedan suponer lesi\u00f3n de los derechos de terceros o del mismo funcionamiento del Sitio Web.<\/li>\n\n\n\n<li>La veracidad y licitud de las informaciones aportadas por el Usuario en los formularios extendidos por\u00a0<strong>MAVE INGENIEROS<\/strong>\u00a0para el acceso a ciertos Contenidos o Servicios ofrecidos por el Sitio Web. En todo caso, el Usuario notificar\u00e1 de forma inmediata a\u00a0<strong>MAVE INGENIEROS<\/strong>\u00a0acerca de cualquier hecho que permita el uso indebido de la informaci\u00f3n registrada en dichos formularios, tales como, pero no solo, el robo, extrav\u00edo, o el acceso no autorizado a identificadores y\/o contrase\u00f1as, con el fin de proceder a su inmediata cancelaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<p>El mero acceso a este Sitio Web no supone entablar ning\u00fan tipo de relaci\u00f3n de car\u00e1cter comercial entre&nbsp;<em>MAVE INGENIEROS<\/em>&nbsp;y el Usuario.<\/p>\n\n\n\n<p>Siempre en el respeto de la legislaci\u00f3n vigente, este Sitio Web de&nbsp;<strong>MAVE INGENIEROS<\/strong>&nbsp;se dirige a todas las personas, sin importar su edad, que puedan acceder y\/o navegar por las p\u00e1ginas del Sitio Web.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>III. ACCESO Y NAVEGACI\u00d3N EN EL SITIO WEB: EXCLUSI\u00d3N DE GARANT\u00cdAS Y RESPONSABILIDAD<\/strong><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">\u200b<\/h3>\n\n\n\n<p><strong>MAVE INGENIEROS<\/strong>&nbsp;no garantiza la continuidad, disponibilidad y utilidad del Sitio Web, ni de los Contenidos o Servicios.&nbsp;<strong>MAVE INGENIEROS<\/strong>&nbsp;har\u00e1 todo lo posible por el buen funcionamiento del Sitio Web, sin embargo, no se responsabiliza ni garantiza que el acceso a este Sitio Web no vaya a ser ininterrumpido o que est\u00e9 libre de error.<\/p>\n\n\n\n<p>Tampoco se responsabiliza o garantiza que el contenido o software al que pueda accederse a trav\u00e9s de este Sitio Web, est\u00e9 libre de error o cause un da\u00f1o al sistema inform\u00e1tico (software y hardware) del Usuario. En ning\u00fan caso&nbsp;<strong>MAVE INGENIEROS<\/strong>&nbsp;ser\u00e1 responsable por las p\u00e9rdidas, da\u00f1os o perjuicios de cualquier tipo que surjan por el acceso, navegaci\u00f3n y el uso del Sitio Web, incluy\u00e9ndose, pero no limit\u00e1ndose, a los ocasionados a los sistemas inform\u00e1ticos o los provocados por la introducci\u00f3n de virus.<\/p>\n\n\n\n<p><strong>MAVE INGENIEROS<\/strong>&nbsp;tampoco se hace responsable de los da\u00f1os que pudiesen ocasionarse a los usuarios por un uso inadecuado de este Sitio Web. En particular, no se hace responsable en modo alguno de las ca\u00eddas, interrupciones, falta o defecto de las telecomunicaciones que pudieran ocurrir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>IV. POL\u00cdTICA DE ENLACES<\/strong><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u200b<\/strong><\/h3>\n\n\n\n<p>Se informa que el Sitio Web de&nbsp;<strong>MAVE INGENIEROS<\/strong>&nbsp;pone o puede poner a disposici\u00f3n de los Usuarios medios de enlace (como, entre otros, links, banners, botones), directorios y motores de b\u00fasqueda que permiten a los Usuarios acceder a sitios web pertenecientes y\/o gestionados por terceros.<\/p>\n\n\n\n<p>La instalaci\u00f3n de estos enlaces, directorios y motores de b\u00fasqueda en el Sitio Web tiene por objeto facilitar a los Usuarios la b\u00fasqueda de y acceso a la informaci\u00f3n disponible en Internet, sin que pueda considerarse una sugerencia, recomendaci\u00f3n o invitaci\u00f3n para la visita de los mismos.<\/p>\n\n\n\n<p><strong>MAVE INGENIEROS<\/strong>&nbsp;no ofrece ni comercializa por s\u00ed ni por medio de terceros los productos y\/o servicios disponibles en dichos sitios enlazados.<\/p>\n\n\n\n<p>Asimismo, tampoco garantizar\u00e1 la disponibilidad t\u00e9cnica, exactitud, veracidad, validez o legalidad de sitios ajenos a su propiedad a los que se pueda acceder por medio de los enlaces.<\/p>\n\n\n\n<p><strong>MAVE INGENIEROS<\/strong>&nbsp;en ning\u00fan caso revisar\u00e1 o controlar\u00e1 el contenido de otros sitios web, as\u00ed como tampoco aprueba, examina ni hace propios los productos y servicios, contenidos, archivos y cualquier otro material existente en los referidos sitios enlazados.<\/p>\n\n\n\n<p>MAVE INGENIEROS no asume ninguna responsabilidad por los da\u00f1os y perjuicios que pudieran producirse por el acceso, uso, calidad o licitud de los contenidos, comunicaciones, opiniones, productos y servicios de los sitios web no gestionados por&nbsp;<strong>MAVE INGENIEROS<\/strong>&nbsp;y que sean enlazados en este Sitio Web.<\/p>\n\n\n\n<p>El Usuario o tercero que realice un hiperv\u00ednculo desde una p\u00e1gina web de otro, distinto, sitio web al Sitio Web de&nbsp;<strong>MAVE INGENIEROS<\/strong>&nbsp;deber\u00e1 saber que:<\/p>\n\n\n\n<p>No se permite la reproducci\u00f3n \u2014total o parcialmente\u2014 de ninguno de los Contenidos y\/o Servicios del Sitio Web sin autorizaci\u00f3n expresa de&nbsp;<strong>MAVE INGENIEROS<\/strong>.<\/p>\n\n\n\n<p>No se permite tampoco ninguna manifestaci\u00f3n falsa, inexacta o incorrecta sobre el Sitio Web de&nbsp;<strong>MAVE INGENIEROS<\/strong>, ni sobre los Contenidos y\/o Servicios del mismo.<\/p>\n\n\n\n<p>A excepci\u00f3n del hiperv\u00ednculo, el sitio web en el que se establezca dicho hiperenlace no contendr\u00e1 ning\u00fan elemento, de este Sitio Web, protegido como propiedad intelectual por el ordenamiento jur\u00eddico espa\u00f1ol, salvo autorizaci\u00f3n expresa de&nbsp;<strong>MAVE INGENIEROS<\/strong>.<\/p>\n\n\n\n<p>El establecimiento del hiperv\u00ednculo no implicar\u00e1 la existencia de relaciones entre&nbsp;<strong>MAVE INGENIEROS<\/strong>&nbsp;y el titular del sitio web desde el cual se realice, ni el conocimiento y aceptaci\u00f3n de&nbsp;<strong>MAVE INGENIEROS<\/strong>&nbsp;de los contenidos, servicios y\/o actividades ofrecidas en dicho sitio web, y viceversa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>V. PROPIEDAD INTELECTUAL E INDUSTRIAL<\/strong><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">\u200b<\/h3>\n\n\n\n<p><strong>MAVE INGENIEROS<\/strong>&nbsp;por s\u00ed o como parte cesionaria, es titular de todos los derechos de propiedad intelectual e industrial del Sitio Web, as\u00ed como de los elementos contenidos en el mismo (a t\u00edtulo enunciativo y no exhaustivo, im\u00e1genes, sonido, audio, v\u00eddeo, software o textos, marcas o logotipos, combinaciones de colores, estructura y dise\u00f1o, selecci\u00f3n de materiales usados, programas de ordenador necesarios para su funcionamiento, acceso y uso, etc.). Ser\u00e1n, por consiguiente, obras protegidas como propiedad intelectual por el ordenamiento jur\u00eddico espa\u00f1ol, si\u00e9ndoles aplicables tanto la normativa espa\u00f1ola y comunitaria en este campo, como los tratados internacionales relativos a la materia y suscritos por Espa\u00f1a.<\/p>\n\n\n\n<p>Todos los derechos reservados. En virtud de lo dispuesto en la Ley de Propiedad Intelectual, quedan expresamente prohibidas la reproducci\u00f3n, la distribuci\u00f3n y la comunicaci\u00f3n p\u00fablica, incluida su modalidad de puesta a disposici\u00f3n, de la totalidad o parte de los contenidos de esta p\u00e1gina web, con fines comerciales, en cualquier soporte y por cualquier medio t\u00e9cnico, sin la autorizaci\u00f3n de&nbsp;<strong>MAVE INGENIEROS.<\/strong><\/p>\n\n\n\n<p>El Usuario se compromete a respetar los derechos de propiedad intelectual e industrial de&nbsp;<strong>MAVE INGENIEROS.<\/strong>&nbsp;Podr\u00e1 visualizar los elementos del Sitio Web o incluso imprimirlos, copiarlos y almacenarlos en el disco duro de su ordenador o en cualquier otro soporte f\u00edsico siempre y cuando sea, exclusivamente, para su uso personal. El Usuario, sin embargo, no podr\u00e1 suprimir, alterar, o manipular cualquier dispositivo de protecci\u00f3n o sistema de seguridad que estuviera instalado en el Sitio Web.<\/p>\n\n\n\n<p>En caso de que el Usuario o tercero considere que cualquiera de los Contenidos del Sitio Web suponga una violaci\u00f3n de los derechos de protecci\u00f3n de la propiedad intelectual, deber\u00e1 comunicarlo inmediatamente a&nbsp;<strong>MAVE INGENIEROS<\/strong>&nbsp;a trav\u00e9s de los datos de contacto del apartado de&nbsp;<strong>INFORMACI\u00d3N GENERAL<\/strong>&nbsp;de este Aviso Legal y Condiciones Generales de Uso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>VI. ACCIONES LEGALES, LEGISLACI\u00d3N APLICABLE Y JURISDICCI\u00d3N<\/strong><\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">\u200b<\/h3>\n\n\n\n<p><strong>MAVE INGENIEROS<\/strong>&nbsp;se reserva la facultad de presentar las acciones civiles o penales que considere necesarias por la utilizaci\u00f3n indebida del Sitio Web y Contenidos, o por el incumplimiento de las presentes Condiciones.<\/p>\n\n\n\n<p>La relaci\u00f3n entre el Usuario y&nbsp;<strong>MAVE INGENIEROS<\/strong>&nbsp;se regir\u00e1 por la normativa vigente y de aplicaci\u00f3n en el territorio espa\u00f1ol. De surgir cualquier controversia en relaci\u00f3n con la interpretaci\u00f3n y\/o a la aplicaci\u00f3n de estas Condiciones las partes someter\u00e1n sus conflictos a la jurisdicci\u00f3n ordinaria someti\u00e9ndose a los jueces y tribunales que correspondan conforme a derecho.<\/p>\n\n\n\n<p>Documento revisado el d\u00eda&nbsp;<strong>18\/10\/2023.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>maveingenieros.com I. INFORMACI\u00d3N GENERAL \u200b En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y el Comercio Electr\u00f3nico (LSSI-CE) de 11 de julio, se facilitan a continuaci\u00f3n los siguientes datos de informaci\u00f3n general de este sitio web: La titularidad de este sitio web,&nbsp;maveingenieros.com, (en adelante, Sitio Web) la ostenta:&nbsp;MAVE INGENIEROS, S.L., provista de&nbsp;NIF: B-81339483&nbsp;e inscrita en: Registro Mercantil de Madrid con los siguientes datos registrales: Tomo 10319, libro 0, folio 177, secci\u00f3n 8\u00aa, cuyo representante es: Manuel Vega, y cuyos datos de contacto son: Direcci\u00f3n: C\/ San Jose, 6 nave 2 Tel\u00e9fono de contacto: 916928520 Email de contacto:&nbsp;mvega@maveingenieros.com II. T\u00c9RMINOS Y CONDICIONES GENERALES DE USO El objeto de las condiciones: El Sitio Web \u200b El objeto de las presentes Condiciones Generales de Uso (en adelante, Condiciones) es regular el acceso y la utilizaci\u00f3n del Sitio Web. A los efectos de las presentes Condiciones se entender\u00e1 como Sitio Web: la apariencia externa de los interfaces de pantalla, tanto de forma est\u00e1tica como de forma din\u00e1mica, es decir, el \u00e1rbol de navegaci\u00f3n; y todos los elementos integrados tanto en los interfaces de pantalla como en el \u00e1rbol de navegaci\u00f3n (en adelante, Contenidos) y todos aquellos servicios o recursos en l\u00ednea que en su caso ofrezca a los Usuarios (en adelante, Servicios). MAVE INGENIEROS&nbsp;se reserva la facultad de modificar, en cualquier momento, y sin aviso previo, la presentaci\u00f3n y configuraci\u00f3n del Sitio Web y de los Contenidos y Servicios que en \u00e9l pudieran estar incorporados. El Usuario reconoce y acepta que en cualquier momento&nbsp;MAVE INGENIEROS&nbsp;pueda interrumpir, desactivar y\/o cancelar cualquiera de estos elementos que se integran en el Sitio Web o el acceso a los mismos. El acceso al Sitio Web por el Usuario tiene car\u00e1cter libre y, por regla general, es gratuito sin que el Usuario tenga que proporcionar una contraprestaci\u00f3n para poder disfrutar de ello, salvo en lo relativo al coste de conexi\u00f3n a trav\u00e9s de la red de telecomunicaciones suministrada por el proveedor de acceso que hubiere contratado el Usuario. La utilizaci\u00f3n de alguno de los Contenidos o Servicios del Sitio Web podr\u00e1 hacerse mediante la suscripci\u00f3n o registro previo del Usuario. El USUARIO \u200b El acceso, la navegaci\u00f3n y uso del Sitio Web, confiere la condici\u00f3n de Usuario, por lo que se aceptan, desde que se inicia la navegaci\u00f3n por el Sitio Web, todas las Condiciones aqu\u00ed establecidas, as\u00ed como sus ulteriores modificaciones, sin perjuicio de la aplicaci\u00f3n de la correspondiente normativa legal de obligado cumplimiento seg\u00fan el caso. Dada la relevancia de lo anterior, se recomienda al Usuario leerlas cada vez que visite el Sitio Web. El Sitio Web de&nbsp;MAVE INGENIEROS&nbsp;proporciona gran diversidad de informaci\u00f3n, servicios y datos. El Usuario asume su responsabilidad para realizar un uso correcto del Sitio Web. Esta responsabilidad se extender\u00e1 a: El mero acceso a este Sitio Web no supone entablar ning\u00fan tipo de relaci\u00f3n de car\u00e1cter comercial entre&nbsp;MAVE INGENIEROS&nbsp;y el Usuario. Siempre en el respeto de la legislaci\u00f3n vigente, este Sitio Web de&nbsp;MAVE INGENIEROS&nbsp;se dirige a todas las personas, sin importar su edad, que puedan acceder y\/o navegar por las p\u00e1ginas del Sitio Web. III. ACCESO Y NAVEGACI\u00d3N EN EL SITIO WEB: EXCLUSI\u00d3N DE GARANT\u00cdAS Y RESPONSABILIDAD \u200b MAVE INGENIEROS&nbsp;no garantiza la continuidad, disponibilidad y utilidad del Sitio Web, ni de los Contenidos o Servicios.&nbsp;MAVE INGENIEROS&nbsp;har\u00e1 todo lo posible por el buen funcionamiento del Sitio Web, sin embargo, no se responsabiliza ni garantiza que el acceso a este Sitio Web no vaya a ser ininterrumpido o que est\u00e9 libre de error. Tampoco se responsabiliza o garantiza que el contenido o software al que pueda accederse a trav\u00e9s de este Sitio Web, est\u00e9 libre de error o cause un da\u00f1o al sistema inform\u00e1tico (software y hardware) del Usuario. En ning\u00fan caso&nbsp;MAVE INGENIEROS&nbsp;ser\u00e1 responsable por las p\u00e9rdidas, da\u00f1os o perjuicios de cualquier tipo que surjan por el acceso, navegaci\u00f3n y el uso del Sitio Web, incluy\u00e9ndose, pero no limit\u00e1ndose, a los ocasionados a los sistemas inform\u00e1ticos o los provocados por la introducci\u00f3n de virus. MAVE INGENIEROS&nbsp;tampoco se hace responsable de los da\u00f1os que pudiesen ocasionarse a los usuarios por un uso inadecuado de este Sitio Web. En particular, no se hace responsable en modo alguno de las ca\u00eddas, interrupciones, falta o defecto de las telecomunicaciones que pudieran ocurrir. IV. POL\u00cdTICA DE ENLACES \u200b Se informa que el Sitio Web de&nbsp;MAVE INGENIEROS&nbsp;pone o puede poner a disposici\u00f3n de los Usuarios medios de enlace (como, entre otros, links, banners, botones), directorios y motores de b\u00fasqueda que permiten a los Usuarios acceder a sitios web pertenecientes y\/o gestionados por terceros. La instalaci\u00f3n de estos enlaces, directorios y motores de b\u00fasqueda en el Sitio Web tiene por objeto facilitar a los Usuarios la b\u00fasqueda de y acceso a la informaci\u00f3n disponible en Internet, sin que pueda considerarse una sugerencia, recomendaci\u00f3n o invitaci\u00f3n para la visita de los mismos. MAVE INGENIEROS&nbsp;no ofrece ni comercializa por s\u00ed ni por medio de terceros los productos y\/o servicios disponibles en dichos sitios enlazados. Asimismo, tampoco garantizar\u00e1 la disponibilidad t\u00e9cnica, exactitud, veracidad, validez o legalidad de sitios ajenos a su propiedad a los que se pueda acceder por medio de los enlaces. MAVE INGENIEROS&nbsp;en ning\u00fan caso revisar\u00e1 o controlar\u00e1 el contenido de otros sitios web, as\u00ed como tampoco aprueba, examina ni hace propios los productos y servicios, contenidos, archivos y cualquier otro material existente en los referidos sitios enlazados. MAVE INGENIEROS no asume ninguna responsabilidad por los da\u00f1os y perjuicios que pudieran producirse por el acceso, uso, calidad o licitud de los contenidos, comunicaciones, opiniones, productos y servicios de los sitios web no gestionados por&nbsp;MAVE INGENIEROS&nbsp;y que sean enlazados en este Sitio Web. El Usuario o tercero que realice un hiperv\u00ednculo desde una p\u00e1gina web de otro, distinto, sitio web al Sitio Web de&nbsp;MAVE INGENIEROS&nbsp;deber\u00e1 saber que: No se permite la reproducci\u00f3n \u2014total o parcialmente\u2014 de ninguno de los Contenidos y\/o Servicios del Sitio Web sin autorizaci\u00f3n expresa de&nbsp;MAVE INGENIEROS. No se permite tampoco ninguna manifestaci\u00f3n falsa, inexacta o incorrecta sobre<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-276","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aviso legal - Mave Ingenieros<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maveingenieros.com\/en\/aviso-legal\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso legal - Mave Ingenieros\" \/>\n<meta property=\"og:description\" content=\"maveingenieros.com I. INFORMACI\u00d3N GENERAL \u200b En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y el Comercio Electr\u00f3nico (LSSI-CE) de 11 de julio, se facilitan a continuaci\u00f3n los siguientes datos de informaci\u00f3n general de este sitio web: La titularidad de este sitio web,&nbsp;maveingenieros.com, (en adelante, Sitio Web) la ostenta:&nbsp;MAVE INGENIEROS, S.L., provista de&nbsp;NIF: B-81339483&nbsp;e inscrita en: Registro Mercantil de Madrid con los siguientes datos registrales: Tomo 10319, libro 0, folio 177, secci\u00f3n 8\u00aa, cuyo representante es: Manuel Vega, y cuyos datos de contacto son: Direcci\u00f3n: C\/ San Jose, 6 nave 2 Tel\u00e9fono de contacto: 916928520 Email de contacto:&nbsp;mvega@maveingenieros.com II. T\u00c9RMINOS Y CONDICIONES GENERALES DE USO El objeto de las condiciones: El Sitio Web \u200b El objeto de las presentes Condiciones Generales de Uso (en adelante, Condiciones) es regular el acceso y la utilizaci\u00f3n del Sitio Web. A los efectos de las presentes Condiciones se entender\u00e1 como Sitio Web: la apariencia externa de los interfaces de pantalla, tanto de forma est\u00e1tica como de forma din\u00e1mica, es decir, el \u00e1rbol de navegaci\u00f3n; y todos los elementos integrados tanto en los interfaces de pantalla como en el \u00e1rbol de navegaci\u00f3n (en adelante, Contenidos) y todos aquellos servicios o recursos en l\u00ednea que en su caso ofrezca a los Usuarios (en adelante, Servicios). MAVE INGENIEROS&nbsp;se reserva la facultad de modificar, en cualquier momento, y sin aviso previo, la presentaci\u00f3n y configuraci\u00f3n del Sitio Web y de los Contenidos y Servicios que en \u00e9l pudieran estar incorporados. El Usuario reconoce y acepta que en cualquier momento&nbsp;MAVE INGENIEROS&nbsp;pueda interrumpir, desactivar y\/o cancelar cualquiera de estos elementos que se integran en el Sitio Web o el acceso a los mismos. El acceso al Sitio Web por el Usuario tiene car\u00e1cter libre y, por regla general, es gratuito sin que el Usuario tenga que proporcionar una contraprestaci\u00f3n para poder disfrutar de ello, salvo en lo relativo al coste de conexi\u00f3n a trav\u00e9s de la red de telecomunicaciones suministrada por el proveedor de acceso que hubiere contratado el Usuario. La utilizaci\u00f3n de alguno de los Contenidos o Servicios del Sitio Web podr\u00e1 hacerse mediante la suscripci\u00f3n o registro previo del Usuario. El USUARIO \u200b El acceso, la navegaci\u00f3n y uso del Sitio Web, confiere la condici\u00f3n de Usuario, por lo que se aceptan, desde que se inicia la navegaci\u00f3n por el Sitio Web, todas las Condiciones aqu\u00ed establecidas, as\u00ed como sus ulteriores modificaciones, sin perjuicio de la aplicaci\u00f3n de la correspondiente normativa legal de obligado cumplimiento seg\u00fan el caso. Dada la relevancia de lo anterior, se recomienda al Usuario leerlas cada vez que visite el Sitio Web. El Sitio Web de&nbsp;MAVE INGENIEROS&nbsp;proporciona gran diversidad de informaci\u00f3n, servicios y datos. El Usuario asume su responsabilidad para realizar un uso correcto del Sitio Web. Esta responsabilidad se extender\u00e1 a: El mero acceso a este Sitio Web no supone entablar ning\u00fan tipo de relaci\u00f3n de car\u00e1cter comercial entre&nbsp;MAVE INGENIEROS&nbsp;y el Usuario. Siempre en el respeto de la legislaci\u00f3n vigente, este Sitio Web de&nbsp;MAVE INGENIEROS&nbsp;se dirige a todas las personas, sin importar su edad, que puedan acceder y\/o navegar por las p\u00e1ginas del Sitio Web. III. ACCESO Y NAVEGACI\u00d3N EN EL SITIO WEB: EXCLUSI\u00d3N DE GARANT\u00cdAS Y RESPONSABILIDAD \u200b MAVE INGENIEROS&nbsp;no garantiza la continuidad, disponibilidad y utilidad del Sitio Web, ni de los Contenidos o Servicios.&nbsp;MAVE INGENIEROS&nbsp;har\u00e1 todo lo posible por el buen funcionamiento del Sitio Web, sin embargo, no se responsabiliza ni garantiza que el acceso a este Sitio Web no vaya a ser ininterrumpido o que est\u00e9 libre de error. Tampoco se responsabiliza o garantiza que el contenido o software al que pueda accederse a trav\u00e9s de este Sitio Web, est\u00e9 libre de error o cause un da\u00f1o al sistema inform\u00e1tico (software y hardware) del Usuario. En ning\u00fan caso&nbsp;MAVE INGENIEROS&nbsp;ser\u00e1 responsable por las p\u00e9rdidas, da\u00f1os o perjuicios de cualquier tipo que surjan por el acceso, navegaci\u00f3n y el uso del Sitio Web, incluy\u00e9ndose, pero no limit\u00e1ndose, a los ocasionados a los sistemas inform\u00e1ticos o los provocados por la introducci\u00f3n de virus. MAVE INGENIEROS&nbsp;tampoco se hace responsable de los da\u00f1os que pudiesen ocasionarse a los usuarios por un uso inadecuado de este Sitio Web. En particular, no se hace responsable en modo alguno de las ca\u00eddas, interrupciones, falta o defecto de las telecomunicaciones que pudieran ocurrir. IV. POL\u00cdTICA DE ENLACES \u200b Se informa que el Sitio Web de&nbsp;MAVE INGENIEROS&nbsp;pone o puede poner a disposici\u00f3n de los Usuarios medios de enlace (como, entre otros, links, banners, botones), directorios y motores de b\u00fasqueda que permiten a los Usuarios acceder a sitios web pertenecientes y\/o gestionados por terceros. La instalaci\u00f3n de estos enlaces, directorios y motores de b\u00fasqueda en el Sitio Web tiene por objeto facilitar a los Usuarios la b\u00fasqueda de y acceso a la informaci\u00f3n disponible en Internet, sin que pueda considerarse una sugerencia, recomendaci\u00f3n o invitaci\u00f3n para la visita de los mismos. MAVE INGENIEROS&nbsp;no ofrece ni comercializa por s\u00ed ni por medio de terceros los productos y\/o servicios disponibles en dichos sitios enlazados. Asimismo, tampoco garantizar\u00e1 la disponibilidad t\u00e9cnica, exactitud, veracidad, validez o legalidad de sitios ajenos a su propiedad a los que se pueda acceder por medio de los enlaces. MAVE INGENIEROS&nbsp;en ning\u00fan caso revisar\u00e1 o controlar\u00e1 el contenido de otros sitios web, as\u00ed como tampoco aprueba, examina ni hace propios los productos y servicios, contenidos, archivos y cualquier otro material existente en los referidos sitios enlazados. MAVE INGENIEROS no asume ninguna responsabilidad por los da\u00f1os y perjuicios que pudieran producirse por el acceso, uso, calidad o licitud de los contenidos, comunicaciones, opiniones, productos y servicios de los sitios web no gestionados por&nbsp;MAVE INGENIEROS&nbsp;y que sean enlazados en este Sitio Web. El Usuario o tercero que realice un hiperv\u00ednculo desde una p\u00e1gina web de otro, distinto, sitio web al Sitio Web de&nbsp;MAVE INGENIEROS&nbsp;deber\u00e1 saber que: No se permite la reproducci\u00f3n \u2014total o parcialmente\u2014 de ninguno de los Contenidos y\/o Servicios del Sitio Web sin autorizaci\u00f3n expresa de&nbsp;MAVE INGENIEROS. No se permite tampoco ninguna manifestaci\u00f3n falsa, inexacta o incorrecta sobre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maveingenieros.com\/en\/aviso-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Mave Ingenieros\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-29T11:17:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maveingenieros.com\\\/aviso-legal\\\/\",\"url\":\"https:\\\/\\\/maveingenieros.com\\\/aviso-legal\\\/\",\"name\":\"Aviso legal - Mave Ingenieros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maveingenieros.com\\\/#website\"},\"datePublished\":\"2024-05-29T11:17:08+00:00\",\"dateModified\":\"2024-05-29T11:17:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maveingenieros.com\\\/aviso-legal\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maveingenieros.com\\\/aviso-legal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maveingenieros.com\\\/aviso-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maveingenieros.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aviso legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maveingenieros.com\\\/#website\",\"url\":\"https:\\\/\\\/maveingenieros.com\\\/\",\"name\":\"Mave Ingenieros\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/maveingenieros.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maveingenieros.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maveingenieros.com\\\/#organization\",\"name\":\"Mave Ingenieros\",\"url\":\"https:\\\/\\\/maveingenieros.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/maveingenieros.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maveingenieros.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-logo.png\",\"contentUrl\":\"https:\\\/\\\/maveingenieros.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-logo.png\",\"width\":1035,\"height\":269,\"caption\":\"Mave Ingenieros\"},\"image\":{\"@id\":\"https:\\\/\\\/maveingenieros.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso legal - Mave Ingenieros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maveingenieros.com\/en\/aviso-legal\/","og_locale":"en_GB","og_type":"article","og_title":"Aviso legal - Mave Ingenieros","og_description":"maveingenieros.com I. INFORMACI\u00d3N GENERAL \u200b En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y el Comercio Electr\u00f3nico (LSSI-CE) de 11 de julio, se facilitan a continuaci\u00f3n los siguientes datos de informaci\u00f3n general de este sitio web: La titularidad de este sitio web,&nbsp;maveingenieros.com, (en adelante, Sitio Web) la ostenta:&nbsp;MAVE INGENIEROS, S.L., provista de&nbsp;NIF: B-81339483&nbsp;e inscrita en: Registro Mercantil de Madrid con los siguientes datos registrales: Tomo 10319, libro 0, folio 177, secci\u00f3n 8\u00aa, cuyo representante es: Manuel Vega, y cuyos datos de contacto son: Direcci\u00f3n: C\/ San Jose, 6 nave 2 Tel\u00e9fono de contacto: 916928520 Email de contacto:&nbsp;mvega@maveingenieros.com II. T\u00c9RMINOS Y CONDICIONES GENERALES DE USO El objeto de las condiciones: El Sitio Web \u200b El objeto de las presentes Condiciones Generales de Uso (en adelante, Condiciones) es regular el acceso y la utilizaci\u00f3n del Sitio Web. A los efectos de las presentes Condiciones se entender\u00e1 como Sitio Web: la apariencia externa de los interfaces de pantalla, tanto de forma est\u00e1tica como de forma din\u00e1mica, es decir, el \u00e1rbol de navegaci\u00f3n; y todos los elementos integrados tanto en los interfaces de pantalla como en el \u00e1rbol de navegaci\u00f3n (en adelante, Contenidos) y todos aquellos servicios o recursos en l\u00ednea que en su caso ofrezca a los Usuarios (en adelante, Servicios). MAVE INGENIEROS&nbsp;se reserva la facultad de modificar, en cualquier momento, y sin aviso previo, la presentaci\u00f3n y configuraci\u00f3n del Sitio Web y de los Contenidos y Servicios que en \u00e9l pudieran estar incorporados. El Usuario reconoce y acepta que en cualquier momento&nbsp;MAVE INGENIEROS&nbsp;pueda interrumpir, desactivar y\/o cancelar cualquiera de estos elementos que se integran en el Sitio Web o el acceso a los mismos. El acceso al Sitio Web por el Usuario tiene car\u00e1cter libre y, por regla general, es gratuito sin que el Usuario tenga que proporcionar una contraprestaci\u00f3n para poder disfrutar de ello, salvo en lo relativo al coste de conexi\u00f3n a trav\u00e9s de la red de telecomunicaciones suministrada por el proveedor de acceso que hubiere contratado el Usuario. La utilizaci\u00f3n de alguno de los Contenidos o Servicios del Sitio Web podr\u00e1 hacerse mediante la suscripci\u00f3n o registro previo del Usuario. El USUARIO \u200b El acceso, la navegaci\u00f3n y uso del Sitio Web, confiere la condici\u00f3n de Usuario, por lo que se aceptan, desde que se inicia la navegaci\u00f3n por el Sitio Web, todas las Condiciones aqu\u00ed establecidas, as\u00ed como sus ulteriores modificaciones, sin perjuicio de la aplicaci\u00f3n de la correspondiente normativa legal de obligado cumplimiento seg\u00fan el caso. Dada la relevancia de lo anterior, se recomienda al Usuario leerlas cada vez que visite el Sitio Web. El Sitio Web de&nbsp;MAVE INGENIEROS&nbsp;proporciona gran diversidad de informaci\u00f3n, servicios y datos. El Usuario asume su responsabilidad para realizar un uso correcto del Sitio Web. Esta responsabilidad se extender\u00e1 a: El mero acceso a este Sitio Web no supone entablar ning\u00fan tipo de relaci\u00f3n de car\u00e1cter comercial entre&nbsp;MAVE INGENIEROS&nbsp;y el Usuario. Siempre en el respeto de la legislaci\u00f3n vigente, este Sitio Web de&nbsp;MAVE INGENIEROS&nbsp;se dirige a todas las personas, sin importar su edad, que puedan acceder y\/o navegar por las p\u00e1ginas del Sitio Web. III. ACCESO Y NAVEGACI\u00d3N EN EL SITIO WEB: EXCLUSI\u00d3N DE GARANT\u00cdAS Y RESPONSABILIDAD \u200b MAVE INGENIEROS&nbsp;no garantiza la continuidad, disponibilidad y utilidad del Sitio Web, ni de los Contenidos o Servicios.&nbsp;MAVE INGENIEROS&nbsp;har\u00e1 todo lo posible por el buen funcionamiento del Sitio Web, sin embargo, no se responsabiliza ni garantiza que el acceso a este Sitio Web no vaya a ser ininterrumpido o que est\u00e9 libre de error. Tampoco se responsabiliza o garantiza que el contenido o software al que pueda accederse a trav\u00e9s de este Sitio Web, est\u00e9 libre de error o cause un da\u00f1o al sistema inform\u00e1tico (software y hardware) del Usuario. En ning\u00fan caso&nbsp;MAVE INGENIEROS&nbsp;ser\u00e1 responsable por las p\u00e9rdidas, da\u00f1os o perjuicios de cualquier tipo que surjan por el acceso, navegaci\u00f3n y el uso del Sitio Web, incluy\u00e9ndose, pero no limit\u00e1ndose, a los ocasionados a los sistemas inform\u00e1ticos o los provocados por la introducci\u00f3n de virus. MAVE INGENIEROS&nbsp;tampoco se hace responsable de los da\u00f1os que pudiesen ocasionarse a los usuarios por un uso inadecuado de este Sitio Web. En particular, no se hace responsable en modo alguno de las ca\u00eddas, interrupciones, falta o defecto de las telecomunicaciones que pudieran ocurrir. IV. POL\u00cdTICA DE ENLACES \u200b Se informa que el Sitio Web de&nbsp;MAVE INGENIEROS&nbsp;pone o puede poner a disposici\u00f3n de los Usuarios medios de enlace (como, entre otros, links, banners, botones), directorios y motores de b\u00fasqueda que permiten a los Usuarios acceder a sitios web pertenecientes y\/o gestionados por terceros. La instalaci\u00f3n de estos enlaces, directorios y motores de b\u00fasqueda en el Sitio Web tiene por objeto facilitar a los Usuarios la b\u00fasqueda de y acceso a la informaci\u00f3n disponible en Internet, sin que pueda considerarse una sugerencia, recomendaci\u00f3n o invitaci\u00f3n para la visita de los mismos. MAVE INGENIEROS&nbsp;no ofrece ni comercializa por s\u00ed ni por medio de terceros los productos y\/o servicios disponibles en dichos sitios enlazados. Asimismo, tampoco garantizar\u00e1 la disponibilidad t\u00e9cnica, exactitud, veracidad, validez o legalidad de sitios ajenos a su propiedad a los que se pueda acceder por medio de los enlaces. MAVE INGENIEROS&nbsp;en ning\u00fan caso revisar\u00e1 o controlar\u00e1 el contenido de otros sitios web, as\u00ed como tampoco aprueba, examina ni hace propios los productos y servicios, contenidos, archivos y cualquier otro material existente en los referidos sitios enlazados. MAVE INGENIEROS no asume ninguna responsabilidad por los da\u00f1os y perjuicios que pudieran producirse por el acceso, uso, calidad o licitud de los contenidos, comunicaciones, opiniones, productos y servicios de los sitios web no gestionados por&nbsp;MAVE INGENIEROS&nbsp;y que sean enlazados en este Sitio Web. El Usuario o tercero que realice un hiperv\u00ednculo desde una p\u00e1gina web de otro, distinto, sitio web al Sitio Web de&nbsp;MAVE INGENIEROS&nbsp;deber\u00e1 saber que: No se permite la reproducci\u00f3n \u2014total o parcialmente\u2014 de ninguno de los Contenidos y\/o Servicios del Sitio Web sin autorizaci\u00f3n expresa de&nbsp;MAVE INGENIEROS. No se permite tampoco ninguna manifestaci\u00f3n falsa, inexacta o incorrecta sobre","og_url":"https:\/\/maveingenieros.com\/en\/aviso-legal\/","og_site_name":"Mave Ingenieros","article_modified_time":"2024-05-29T11:17:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/maveingenieros.com\/aviso-legal\/","url":"https:\/\/maveingenieros.com\/aviso-legal\/","name":"Aviso legal - Mave Ingenieros","isPartOf":{"@id":"https:\/\/maveingenieros.com\/#website"},"datePublished":"2024-05-29T11:17:08+00:00","dateModified":"2024-05-29T11:17:37+00:00","breadcrumb":{"@id":"https:\/\/maveingenieros.com\/aviso-legal\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maveingenieros.com\/aviso-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maveingenieros.com\/aviso-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maveingenieros.com\/"},{"@type":"ListItem","position":2,"name":"Aviso legal"}]},{"@type":"WebSite","@id":"https:\/\/maveingenieros.com\/#website","url":"https:\/\/maveingenieros.com\/","name":"Mave Ingenieros","description":"","publisher":{"@id":"https:\/\/maveingenieros.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maveingenieros.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/maveingenieros.com\/#organization","name":"Mave Ingenieros","url":"https:\/\/maveingenieros.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/maveingenieros.com\/#\/schema\/logo\/image\/","url":"https:\/\/maveingenieros.com\/wp-content\/uploads\/2024\/05\/cropped-logo.png","contentUrl":"https:\/\/maveingenieros.com\/wp-content\/uploads\/2024\/05\/cropped-logo.png","width":1035,"height":269,"caption":"Mave Ingenieros"},"image":{"@id":"https:\/\/maveingenieros.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/maveingenieros.com\/en\/wp-json\/wp\/v2\/pages\/276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maveingenieros.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/maveingenieros.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/maveingenieros.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maveingenieros.com\/en\/wp-json\/wp\/v2\/comments?post=276"}],"version-history":[{"count":0,"href":"https:\/\/maveingenieros.com\/en\/wp-json\/wp\/v2\/pages\/276\/revisions"}],"wp:attachment":[{"href":"https:\/\/maveingenieros.com\/en\/wp-json\/wp\/v2\/media?parent=276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}